{"id":1373,"date":"2019-11-12T21:13:48","date_gmt":"2019-11-13T03:13:48","guid":{"rendered":"https:\/\/www.capa8.com\/familias\/?p=1373"},"modified":"2019-11-12T21:13:48","modified_gmt":"2019-11-13T03:13:48","slug":"ransomware-obliga-a-distrito-escolar-de-nuevo-mexico-a-depurar-30000-dispositivos","status":"publish","type":"post","link":"https:\/\/escuelasciberseguras.com\/blog\/ransomware-obliga-a-distrito-escolar-de-nuevo-mexico-a-depurar-30000-dispositivos\/","title":{"rendered":"Ransomware obliga a distrito escolar de Nuevo M\u00e9xico a depurar 30,000 dispositivos"},"content":{"rendered":"\n<p class=\"has-drop-cap\">El <strong>ransomware<\/strong> es una amenaza que tiene particularmente de \u00abcabeza\u00bb a las instituciones educativas en los Estados Unidos, y del cual estaremos escuchando de una manera recurrente en este sector en toda Latinoam\u00e9rica en los pr\u00f3ximos meses. <\/p>\n\n\n\n<p>El portal <a rel=\"noreferrer noopener\" aria-label=\"EDSCOOP (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/edscoop.com\/ransomware-forces-new-mexico-school-district-scrub-30000-devices\/\" target=\"_blank\">edscoop<\/a> public\u00f3 que un distrito escolar de Nuevo M\u00e9xico que ten\u00eda sus sistemas infectados por ransomware el mes pasado, ahora <strong>tiene que limpiar los discos duros de unos 30,000 dispositivos.<\/strong> El sistema del distrito fue infectado con ransomware, un programa malicioso dise\u00f1ado para bloquear el acceso a computadoras o sistemas de datos hasta que se pague un rescate.&nbsp;A menudo se transmite al visitar sitios web infectados o al abrir correos electr\u00f3nicos de \u00abphishing\u00bb.<\/p>\n\n\n\n<p>En una conferencia de prensa celebrada por el Distrito de Escuelas P\u00fablicas de Las Cruces, la superintendente interina Karen Trujillo inform\u00f3 que el ataque cibern\u00e9tico ha mantenido las <strong>39 escuelas del distrito fuera de l\u00ednea desde que se detect\u00f3 el malware el 29 de octubre.<\/strong> <\/p>\n\n\n\n<p>Las autoridades escolares se\u00f1alaron que no se involucraron con el ciberatacante, por lo que <strong>la recuperaci\u00f3n consistir\u00e1 en reformatear los discos duros de miles de computadoras de escritorio, computadoras port\u00e1tiles y otros dispositivos, y luego reinstalar los sistemas operativos<\/strong>.<\/p>\n\n\n\n<p>Aunque, seg\u00fan los informes, el sistema de correo electr\u00f3nico basado en la nube del distrito no se vio afectado, los administradores del distrito no estaban dispuestos a arriesgarse a adivinar cu\u00e1ndo se volver\u00edan a conectar las computadoras de las escuelas a Internet.<\/p>\n\n\n\n<p>Los administradores tampoco proporcionaron cifras sobre el costo de la interrupci\u00f3n, pero mencionaron que los fondos y subvenciones federales utilizadas para subsidiar los servicios de Internet de banda ancha, tambi\u00e9n podr\u00edan utilizarse para compensar los costos de ransomware del distrito.<\/p>\n\n\n\n<p>Trujillo dijo que no se cancelar\u00e1n las clases.<\/p>\n\n\n\n<p><strong>El ataque contra Las Cruces es solo uno de los 23 ataques de ransomware en distritos escolares en los EE. UU. desde agosto. <\/strong><\/p>\n\n\n\n<p> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ransomware es una amenaza que tiene particularmente de \u00abcabeza\u00bb a las instituciones educativas en los Estados Unidos, y del cual estaremos escuchando de una manera recurrente en este sector en toda Latinoam\u00e9rica en los pr\u00f3ximos meses. El portal edscoop public\u00f3 que un distrito escolar de Nuevo M\u00e9xico que ten\u00eda sus sistemas infectados por ransomware [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1374,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[39],"tags":[],"_links":{"self":[{"href":"https:\/\/escuelasciberseguras.com\/blog\/wp-json\/wp\/v2\/posts\/1373"}],"collection":[{"href":"https:\/\/escuelasciberseguras.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/escuelasciberseguras.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/escuelasciberseguras.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/escuelasciberseguras.com\/blog\/wp-json\/wp\/v2\/comments?post=1373"}],"version-history":[{"count":0,"href":"https:\/\/escuelasciberseguras.com\/blog\/wp-json\/wp\/v2\/posts\/1373\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/escuelasciberseguras.com\/blog\/wp-json\/wp\/v2\/media\/1374"}],"wp:attachment":[{"href":"https:\/\/escuelasciberseguras.com\/blog\/wp-json\/wp\/v2\/media?parent=1373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/escuelasciberseguras.com\/blog\/wp-json\/wp\/v2\/categories?post=1373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/escuelasciberseguras.com\/blog\/wp-json\/wp\/v2\/tags?post=1373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}